{"id":6994,"date":"2019-12-17T00:00:00","date_gmt":"2019-12-16T23:00:00","guid":{"rendered":"https:\/\/acm.mc\/index.php\/edition\/rallye-monte-carlo-edition-2020\/official-notice-board\/"},"modified":"2019-12-17T00:00:00","modified_gmt":"2019-12-16T23:00:00","slug":"official-notice-board","status":"publish","type":"edition","link":"https:\/\/acm.mc\/en\/edition\/88e-rallye-automobile-monte%e2%80%91carlo\/official-notice-board\/","title":{"rendered":"Official Notice Board"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"parent":6844,"menu_order":1126,"template":"","categories":[],"class_list":["post-6994","edition","type-edition","status-publish","hentry"],"acf":{"contenu_des_pages":null,"icone_quick_link":null,"afficher_la_page_en_grise":null,"activer_la_redirection":null,"redirection":null},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Official Notice Board - Automobile Club de Monaco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acm.mc\/en\/edition\/88e-rallye-automobile-monte%e2%80%91carlo\/official-notice-board\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Official Notice Board - Automobile Club de Monaco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acm.mc\/en\/edition\/88e-rallye-automobile-monte%e2%80%91carlo\/official-notice-board\/\" \/>\n<meta property=\"og:site_name\" content=\"Automobile Club de Monaco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/automobileclubmonacoMC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ACM_Media\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acm.mc\\\/en\\\/edition\\\/88e-rallye-automobile-monte%e2%80%91carlo\\\/official-notice-board\\\/\",\"url\":\"https:\\\/\\\/acm.mc\\\/en\\\/edition\\\/88e-rallye-automobile-monte%e2%80%91carlo\\\/official-notice-board\\\/\",\"name\":\"Official Notice Board - Automobile Club de Monaco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acm.mc\\\/en\\\/#website\"},\"datePublished\":\"2019-12-16T23:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acm.mc\\\/en\\\/edition\\\/88e-rallye-automobile-monte%e2%80%91carlo\\\/official-notice-board\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acm.mc\\\/en\\\/edition\\\/88e-rallye-automobile-monte%e2%80%91carlo\\\/official-notice-board\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acm.mc\\\/en\\\/edition\\\/88e-rallye-automobile-monte%e2%80%91carlo\\\/official-notice-board\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acm.mc\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Editions\",\"item\":\"https:\\\/\\\/acm.mc\\\/en\\\/edition\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"88e Rallye Automobile Monte\u2011Carlo\",\"item\":\"https:\\\/\\\/acm.mc\\\/en\\\/edition\\\/88e-rallye-automobile-monte%e2%80%91carlo\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Official Notice Board\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acm.mc\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/acm.mc\\\/en\\\/\",\"name\":\"Automobile Club de Monaco\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acm.mc\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Official Notice Board - Automobile Club de Monaco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acm.mc\/en\/edition\/88e-rallye-automobile-monte%e2%80%91carlo\/official-notice-board\/","og_locale":"en_US","og_type":"article","og_title":"Official Notice Board - Automobile Club de Monaco","og_url":"https:\/\/acm.mc\/en\/edition\/88e-rallye-automobile-monte%e2%80%91carlo\/official-notice-board\/","og_site_name":"Automobile Club de Monaco","article_publisher":"https:\/\/www.facebook.com\/automobileclubmonacoMC","twitter_card":"summary_large_image","twitter_site":"@ACM_Media","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/acm.mc\/en\/edition\/88e-rallye-automobile-monte%e2%80%91carlo\/official-notice-board\/","url":"https:\/\/acm.mc\/en\/edition\/88e-rallye-automobile-monte%e2%80%91carlo\/official-notice-board\/","name":"Official Notice Board - Automobile Club de Monaco","isPartOf":{"@id":"https:\/\/acm.mc\/en\/#website"},"datePublished":"2019-12-16T23:00:00+00:00","breadcrumb":{"@id":"https:\/\/acm.mc\/en\/edition\/88e-rallye-automobile-monte%e2%80%91carlo\/official-notice-board\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acm.mc\/en\/edition\/88e-rallye-automobile-monte%e2%80%91carlo\/official-notice-board\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acm.mc\/en\/edition\/88e-rallye-automobile-monte%e2%80%91carlo\/official-notice-board\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acm.mc\/en\/"},{"@type":"ListItem","position":2,"name":"Editions","item":"https:\/\/acm.mc\/en\/edition\/"},{"@type":"ListItem","position":3,"name":"88e Rallye Automobile Monte\u2011Carlo","item":"https:\/\/acm.mc\/en\/edition\/88e-rallye-automobile-monte%e2%80%91carlo\/"},{"@type":"ListItem","position":4,"name":"Official Notice Board"}]},{"@type":"WebSite","@id":"https:\/\/acm.mc\/en\/#website","url":"https:\/\/acm.mc\/en\/","name":"Automobile Club de Monaco","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acm.mc\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/acm.mc\/en\/wp-json\/wp\/v2\/editions\/6994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acm.mc\/en\/wp-json\/wp\/v2\/editions"}],"about":[{"href":"https:\/\/acm.mc\/en\/wp-json\/wp\/v2\/types\/edition"}],"up":[{"embeddable":true,"href":"https:\/\/acm.mc\/en\/wp-json\/wp\/v2\/editions\/6844"}],"wp:attachment":[{"href":"https:\/\/acm.mc\/en\/wp-json\/wp\/v2\/media?parent=6994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acm.mc\/en\/wp-json\/wp\/v2\/categories?post=6994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}