{"id":10606481,"date":"2025-07-09T16:51:21","date_gmt":"2025-07-09T14:51:21","guid":{"rendered":"https:\/\/acm.mc\/?post_type=edition&#038;p=10606481"},"modified":"2025-10-19T09:56:53","modified_gmt":"2025-10-19T07:56:53","slug":"classification-results","status":"publish","type":"epreuves","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/","title":{"rendered":"Classification &#8211; Results"},"content":{"rendered":"","protected":false},"featured_media":0,"parent":10606480,"menu_order":208,"template":"","categories":[63],"class_list":["post-10606481","epreuves","type-epreuves","status-publish","hentry","category-e-rallye-monte-carlo-en","millesime-497"],"acf":{"icone_quick_link":"<i class=\"fas fa-list-ol\" aria-hidden=\"true\"><\/i>","afficher_la_page_en_grise":false,"activer_la_redirection":false,"contenu_des_pages":[{"acf_fc_layout":"bloc-contenu","contenu":"<p><iframe src=\"https:\/\/eramc2025.jbtc.be\/\" width=\"100%\" height=\"1200\" frameborder=\"0\"><\/iframe><\/p>\n"},{"acf_fc_layout":"bloc-document-telecharger","titre":"Results","module_document":[{"categorie_de_document":"","transformer_la_categorie_en_accordeon":false,"documents":[{"titre_de_document":"RS 1","document":{"ID":10608141,"id":10608141,"title":"ALUR-ERAMC2025_SR_1_-_Detailed","filename":"ALUR-ERAMC2025_SR_1_-_Detailed.pdf","filesize":223186,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/07\/ALUR-ERAMC2025_SR_1_-_Detailed.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/alur-eramc2025_sr_1_-_detailed-2\/","alt":"","author":"2","description":"","caption":"","name":"alur-eramc2025_sr_1_-_detailed-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-15 22:21:18","modified":"2025-10-15 22:21:18","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"RS 2","document":{"ID":10608143,"id":10608143,"title":"ajV--ERAMC2025_SR_2_-_Detailed","filename":"ajV-ERAMC2025_SR_2_-_Detailed.pdf","filesize":224161,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/07\/ajV-ERAMC2025_SR_2_-_Detailed.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/ajv-eramc2025_sr_2_-_detailed-2\/","alt":"","author":"2","description":"","caption":"","name":"ajv-eramc2025_sr_2_-_detailed-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-15 22:21:30","modified":"2025-10-15 22:21:30","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"RS 3","document":{"ID":10608236,"id":10608236,"title":"nYRT-ERAMC2025_SR_3_-_Detailed","filename":"nYRT-ERAMC2025_SR_3_-_Detailed.pdf","filesize":222002,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/07\/nYRT-ERAMC2025_SR_3_-_Detailed.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/nyrt-eramc2025_sr_3_-_detailed-2\/","alt":"","author":"2","description":"","caption":"","name":"nyrt-eramc2025_sr_3_-_detailed-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-16 16:43:23","modified":"2025-10-16 16:43:23","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"RS 4","document":{"ID":10608238,"id":10608238,"title":"fjxx-ERAMC2025_SR_4_-_Detailed","filename":"fjxx-ERAMC2025_SR_4_-_Detailed.pdf","filesize":223325,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/07\/fjxx-ERAMC2025_SR_4_-_Detailed.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/fjxx-eramc2025_sr_4_-_detailed-2\/","alt":"","author":"2","description":"","caption":"","name":"fjxx-eramc2025_sr_4_-_detailed-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-16 16:43:24","modified":"2025-10-16 16:43:24","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"RS 5","document":{"ID":10608240,"id":10608240,"title":"QSbv-ERAMC2025_SR_5_-_Detailed","filename":"QSbv-ERAMC2025_SR_5_-_Detailed.pdf","filesize":223962,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/07\/QSbv-ERAMC2025_SR_5_-_Detailed.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/qsbv-eramc2025_sr_5_-_detailed-2\/","alt":"","author":"2","description":"","caption":"","name":"qsbv-eramc2025_sr_5_-_detailed-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-16 16:43:25","modified":"2025-10-16 16:43:25","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"RS 6","document":{"ID":10608242,"id":10608242,"title":"Gvm5-ERAMC2025_SR_6_-_Detailed","filename":"Gvm5-ERAMC2025_SR_6_-_Detailed.pdf","filesize":224787,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/07\/Gvm5-ERAMC2025_SR_6_-_Detailed.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/gvm5-eramc2025_sr_6_-_detailed-2\/","alt":"","author":"2","description":"","caption":"","name":"gvm5-eramc2025_sr_6_-_detailed-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-16 16:43:26","modified":"2025-10-16 16:43:26","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"RS 7","document":{"ID":10608333,"id":10608333,"title":"n985-ERAMC2025_SR_7_-_Detailed","filename":"n985-ERAMC2025_SR_7_-_Detailed.pdf","filesize":220853,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/07\/n985-ERAMC2025_SR_7_-_Detailed.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/n985-eramc2025_sr_7_-_detailed-2\/","alt":"","author":"1","description":"","caption":"","name":"n985-eramc2025_sr_7_-_detailed-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-17 14:34:33","modified":"2025-10-17 14:34:33","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"RS 8","document":{"ID":10608335,"id":10608335,"title":"twor-ERAMC2025_SR_8_-_Detailed","filename":"twor-ERAMC2025_SR_8_-_Detailed.pdf","filesize":219694,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/07\/twor-ERAMC2025_SR_8_-_Detailed.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/twor-eramc2025_sr_8_-_detailed-2\/","alt":"","author":"1","description":"","caption":"","name":"twor-eramc2025_sr_8_-_detailed-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-17 14:34:34","modified":"2025-10-17 14:34:34","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"RS 9","document":{"ID":10608337,"id":10608337,"title":"gJYh-ERAMC2025_SR_9_-_Detailed","filename":"gJYh-ERAMC2025_SR_9_-_Detailed.pdf","filesize":221535,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/07\/gJYh-ERAMC2025_SR_9_-_Detailed.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/gjyh-eramc2025_sr_9_-_detailed-2\/","alt":"","author":"1","description":"","caption":"","name":"gjyh-eramc2025_sr_9_-_detailed-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-17 14:34:35","modified":"2025-10-17 14:34:35","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"RS 10","document":{"ID":10608339,"id":10608339,"title":"95er-ERAMC2025_SR_10_-_Detailed","filename":"95er-ERAMC2025_SR_10_-_Detailed.pdf","filesize":222169,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/07\/95er-ERAMC2025_SR_10_-_Detailed.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/95er-eramc2025_sr_10_-_detailed-2\/","alt":"","author":"1","description":"","caption":"","name":"95er-eramc2025_sr_10_-_detailed-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-17 14:52:24","modified":"2025-10-17 14:52:24","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"RS 11","document":{"ID":10608493,"id":10608493,"title":"jk_2-ERAMC2025_SR_11_-_Detailed","filename":"jk_2-ERAMC2025_SR_11_-_Detailed.pdf","filesize":220464,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/10\/jk_2-ERAMC2025_SR_11_-_Detailed.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/jk_2-eramc2025_sr_11_-_detailed-2\/","alt":"","author":"1","description":"","caption":"","name":"jk_2-eramc2025_sr_11_-_detailed-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-18 16:59:49","modified":"2025-10-18 17:03:46","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"RS 12","document":{"ID":10608495,"id":10608495,"title":"qz6U-ERAMC2025_SR_12_-_Detailed","filename":"qz6U-ERAMC2025_SR_12_-_Detailed.pdf","filesize":221842,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/10\/qz6U-ERAMC2025_SR_12_-_Detailed.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/qz6u-eramc2025_sr_12_-_detailed-2\/","alt":"","author":"1","description":"","caption":"","name":"qz6u-eramc2025_sr_12_-_detailed-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-18 16:59:51","modified":"2025-10-18 17:03:46","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"RS 13","document":{"ID":10608497,"id":10608497,"title":"5pqj-ERAMC2025_SR_13_-_Detailed","filename":"5pqj-ERAMC2025_SR_13_-_Detailed.pdf","filesize":222143,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/10\/5pqj-ERAMC2025_SR_13_-_Detailed.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/5pqj-eramc2025_sr_13_-_detailed-2\/","alt":"","author":"1","description":"","caption":"","name":"5pqj-eramc2025_sr_13_-_detailed-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-18 16:59:52","modified":"2025-10-18 17:03:47","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"RS 14","document":{"ID":10608499,"id":10608499,"title":"_x0G-ERAMC2025_SR_14_-_Detailed","filename":"x0G-ERAMC2025_SR_14_-_Detailed.pdf","filesize":219576,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/10\/x0G-ERAMC2025_SR_14_-_Detailed.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/_x0g-eramc2025_sr_14_-_detailed-2\/","alt":"","author":"1","description":"","caption":"","name":"_x0g-eramc2025_sr_14_-_detailed-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-18 16:59:53","modified":"2025-10-18 17:03:47","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"E-Power Stage","document":false,"hide_document":true}],"hide_categorie":false}],"activer_la_recherche":false},{"acf_fc_layout":"bloc-document-telecharger","titre":"Classification","module_document":[{"categorie_de_document":"","transformer_la_categorie_en_accordeon":false,"documents":[{"titre_de_document":"Provisional general classification after Leg 1","document":{"ID":10608184,"id":10608184,"title":"hLy7-ERAMC2025_Provisional_Overall_after_Leg_1","filename":"hLy7-ERAMC2025_Provisional_Overall_after_Leg_1.pdf","filesize":206754,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/07\/hLy7-ERAMC2025_Provisional_Overall_after_Leg_1.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/hly7-eramc2025_provisional_overall_after_leg_1-2\/","alt":"","author":"2","description":"","caption":"","name":"hly7-eramc2025_provisional_overall_after_leg_1-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-16 10:21:13","modified":"2025-10-16 10:21:13","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"Provisional general classification after Leg 2","document":{"ID":10608249,"id":10608249,"title":"_KKx-ERAMC2025_Provisional_Overall_after_Leg_2","filename":"KKx-ERAMC2025_Provisional_Overall_after_Leg_2.pdf","filesize":211284,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/10\/KKx-ERAMC2025_Provisional_Overall_after_Leg_2.pdf","link":"https:\/\/acm.mc\/en\/leg-2-surprises-at-the-heart-of-an-unprecedented-day\/_kkx-eramc2025_provisional_overall_after_leg_2-2\/","alt":"","author":"2","description":"","caption":"","name":"_kkx-eramc2025_provisional_overall_after_leg_2-2","status":"inherit","uploaded_to":10608255,"date":"2025-10-16 19:03:20","modified":"2025-10-16 19:10:58","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"Provisional general classification after Leg 3","document":{"ID":10608387,"id":10608387,"title":"0lgZ-ERAMC2025_Provisional_Overall_after_Leg_3","filename":"0lgZ-ERAMC2025_Provisional_Overall_after_Leg_3.pdf","filesize":209884,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/10\/0lgZ-ERAMC2025_Provisional_Overall_after_Leg_3.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/0lgz-eramc2025_provisional_overall_after_leg_3-2\/","alt":"","author":"1","description":"","caption":"","name":"0lgz-eramc2025_provisional_overall_after_leg_3-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-17 19:18:48","modified":"2025-10-17 19:42:21","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"Provisional general classification after Leg 4","document":{"ID":10608501,"id":10608501,"title":"yiaq-ERAMC2025_Provisional_Overall_after_Leg_4","filename":"yiaq-ERAMC2025_Provisional_Overall_after_Leg_4.pdf","filesize":211288,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/10\/yiaq-ERAMC2025_Provisional_Overall_after_Leg_4.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/yiaq-eramc2025_provisional_overall_after_leg_4-2\/","alt":"","author":"1","description":"","caption":"","name":"yiaq-eramc2025_provisional_overall_after_leg_4-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-18 16:59:55","modified":"2025-10-18 17:03:47","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"Final overall classification","document":{"ID":10608535,"id":10608535,"title":"0fFz-ERAMC2025_Final_Overall_Classification","filename":"0fFz-ERAMC2025_Final_Overall_Classification.pdf","filesize":210602,"url":"https:\/\/acm.mc\/wp-content\/uploads\/2025\/07\/0fFz-ERAMC2025_Final_Overall_Classification.pdf","link":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/0ffz-eramc2025_final_overall_classification-2\/","alt":"","author":"1","description":"","caption":"","name":"0ffz-eramc2025_final_overall_classification-2","status":"inherit","uploaded_to":10606481,"date":"2025-10-19 07:56:12","modified":"2025-10-19 07:56:12","menu_order":0,"mime_type":"application\/pdf","type":"application","subtype":"pdf","icon":"https:\/\/acm.mc\/wp-includes\/images\/media\/document.png"},"hide_document":false},{"titre_de_document":"Final classification by team","document":false,"hide_document":true},{"titre_de_document":"Final classification ECO-R FIA Bridgestone Cup","document":false,"hide_document":true}],"hide_categorie":false}],"activer_la_recherche":false}],"redirection":{"title":"Classification - Results","url":"https:\/\/acm.mc\/en\/edition\/6e-e-rallye-monte-carlo\/espace-concurrents\/official-notice-board\/classification-results\/","target":""}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Classification - Results - Automobile Club de Monaco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Classification - Results - Automobile Club de Monaco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/\" \/>\n<meta property=\"og:site_name\" content=\"Automobile Club de Monaco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/automobileclubmonacoMC\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-19T07:56:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ACM_Media\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/acm.mc\\\/en\\\/epreuves\\\/e-rallye-monte-carlo\\\/event\\\/classification-results\\\/\",\"url\":\"https:\\\/\\\/acm.mc\\\/en\\\/epreuves\\\/e-rallye-monte-carlo\\\/event\\\/classification-results\\\/\",\"name\":\"Classification - Results - Automobile Club de Monaco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/acm.mc\\\/en\\\/#website\"},\"datePublished\":\"2025-07-09T14:51:21+00:00\",\"dateModified\":\"2025-10-19T07:56:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/acm.mc\\\/en\\\/epreuves\\\/e-rallye-monte-carlo\\\/event\\\/classification-results\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/acm.mc\\\/en\\\/epreuves\\\/e-rallye-monte-carlo\\\/event\\\/classification-results\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/acm.mc\\\/en\\\/epreuves\\\/e-rallye-monte-carlo\\\/event\\\/classification-results\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/acm.mc\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/acm.mc\\\/en\\\/epreuves\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"E-Rallye Monte-Carlo\",\"item\":\"https:\\\/\\\/acm.mc\\\/en\\\/epreuves\\\/e-rallye-monte-carlo\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Event\",\"item\":\"https:\\\/\\\/acm.mc\\\/en\\\/epreuves\\\/e-rallye-monte-carlo\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Classification &#8211; Results\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/acm.mc\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/acm.mc\\\/en\\\/\",\"name\":\"Automobile Club de Monaco\",\"description\":\"Un site utilisant WordPress\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/acm.mc\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Classification - Results - Automobile Club de Monaco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/","og_locale":"en_US","og_type":"article","og_title":"Classification - Results - Automobile Club de Monaco","og_url":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/","og_site_name":"Automobile Club de Monaco","article_publisher":"https:\/\/www.facebook.com\/automobileclubmonacoMC","article_modified_time":"2025-10-19T07:56:53+00:00","twitter_card":"summary_large_image","twitter_site":"@ACM_Media","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/","url":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/","name":"Classification - Results - Automobile Club de Monaco","isPartOf":{"@id":"https:\/\/acm.mc\/en\/#website"},"datePublished":"2025-07-09T14:51:21+00:00","dateModified":"2025-10-19T07:56:53+00:00","breadcrumb":{"@id":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/classification-results\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/acm.mc\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/acm.mc\/en\/epreuves\/"},{"@type":"ListItem","position":3,"name":"E-Rallye Monte-Carlo","item":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/"},{"@type":"ListItem","position":4,"name":"Event","item":"https:\/\/acm.mc\/en\/epreuves\/e-rallye-monte-carlo\/event\/"},{"@type":"ListItem","position":5,"name":"Classification &#8211; Results"}]},{"@type":"WebSite","@id":"https:\/\/acm.mc\/en\/#website","url":"https:\/\/acm.mc\/en\/","name":"Automobile Club de Monaco","description":"Un site utilisant WordPress","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/acm.mc\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/acm.mc\/en\/wp-json\/wp\/v2\/epreuves\/10606481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acm.mc\/en\/wp-json\/wp\/v2\/epreuves"}],"about":[{"href":"https:\/\/acm.mc\/en\/wp-json\/wp\/v2\/types\/epreuves"}],"up":[{"embeddable":true,"href":"https:\/\/acm.mc\/en\/wp-json\/wp\/v2\/epreuves\/10606480"}],"wp:attachment":[{"href":"https:\/\/acm.mc\/en\/wp-json\/wp\/v2\/media?parent=10606481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acm.mc\/en\/wp-json\/wp\/v2\/categories?post=10606481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}